{"id":25185,"date":"2026-09-01T09:53:42","date_gmt":"2026-09-01T12:53:42","guid":{"rendered":"https:\/\/jornalpontomais.com\/site\/?p=25185"},"modified":"2026-09-01T09:54:04","modified_gmt":"2026-09-01T12:54:04","slug":"arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027","status":"publish","type":"post","link":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/","title":{"rendered":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Criado pela reforma tribut\u00e1ria, o Imposto Seletivo (IS), apelidado como &#8220;imposto do pecado&#8221;, dever\u00e1 arrecadar R$ 41,9 bilh\u00f5es em 2027. A previs\u00e3o foi inclu\u00edda no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA), enviado nesta segunda-feira (31) ao Congresso Nacional.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1701151&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1701151&amp;o=node\"><br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O tributo ser\u00e1 aplicado a produtos e atividades considerados prejudiciais \u00e0 sa\u00fade ou ao meio ambiente. Entre eles est\u00e3o cigarros, bebidas alco\u00f3licas, refrigerantes, alguns tipos de ve\u00edculos, al\u00e9m da extra\u00e7\u00e3o de bens minerais, loterias, apostas e jogos de fantasy sports.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cobran\u00e7a come\u00e7a em 2027, mas a regulamenta\u00e7\u00e3o do imposto ainda precisa ser aprovada pelo Congresso. O governo ainda n\u00e3o enviou a proposta espec\u00edfica que definir\u00e1 as regras de funcionamento do tributo.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Produtos taxados<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lista prevista para o Imposto Seletivo inclui:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Cigarros e outros produtos de tabaco;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Bebidas alco\u00f3licas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Refrigerantes e outras bebidas a\u00e7ucaradas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Ve\u00edculos, conforme caracter\u00edsticas e n\u00edvel de emiss\u00e3o de poluentes;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Extra\u00e7\u00e3o de bens minerais;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; Loterias e apostas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u00a0 \u00a0 Bets e fantasy sports.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o Minist\u00e9rio da Fazenda, a estrat\u00e9gia inicial \u00e9 preservar, durante o per\u00edodo de transi\u00e7\u00e3o, uma carga tribut\u00e1ria semelhante \u00e0 atualmente aplicada aos produtos. Em uma etapa posterior, as al\u00edquotas poder\u00e3o ser elevadas pelo chamado efeito regulat\u00f3rio, com o objetivo de desestimular o consumo de produtos considerados nocivos.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em entrevista coletiva para explicar o PLOA de 2027, o ministro da Fazenda, Dario Durigan, afirmou que a estimativa de arrecada\u00e7\u00e3o busca preservar a carga atual incidente sobre setores que s\u00e3o tributados pelo Imposto sobre Produtos Industrializados (IPI).<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No caso das apostas, a tributa\u00e7\u00e3o ser\u00e1 uma novidade, porque as chamadas bets n\u00e3o est\u00e3o sujeitas ao IPI. Segundo Durigan, o governo pretende evitar uma al\u00edquota t\u00e3o baixa que seja irrelevante ou t\u00e3o alta que estimule a migra\u00e7\u00e3o das plataformas para a ilegalidade.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Impacto na sa\u00fade<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O governo utiliza tamb\u00e9m argumentos relacionados aos custos provocados pelo consumo desses produtos para justificar a tributa\u00e7\u00e3o.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o Minist\u00e9rio da Sa\u00fade, um estudo da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) estimou que o consumo de \u00e1lcool gerou, em 2019, R$ 18,8 bilh\u00f5es em custos. Desse total, R$ 1,1 bilh\u00e3o correspondeu a despesas federais diretas com hospitaliza\u00e7\u00f5es e procedimentos ambulatoriais no SUS.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No caso do tabagismo, as doen\u00e7as relacionadas ao consumo de cigarros geram R$ 153,5 bilh\u00f5es em custos anuais, segundo estimativa do Minist\u00e9rio da Sa\u00fade. O valor inclui despesas diretas e perdas de produtividade.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os n\u00fameros apresentados pelo Minist\u00e9rio da Sa\u00fade mostram ainda que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; R$ 86,3 bilh\u00f5es s\u00e3o custos indiretos associados ao tabagismo;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp; &nbsp; R$ 8 bilh\u00f5es s\u00e3o arrecadados anualmente em tributos federais sobre cigarros;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022\u00a0 \u00a0 R$ 3 bilh\u00f5es s\u00e3o os custos estimados ao SUS com doen\u00e7as relacionadas ao consumo de bebidas ultraprocessadas, como refrigerantes.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reforma tribut\u00e1ria<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Imposto Seletivo integra o novo sistema de tributa\u00e7\u00e3o sobre o consumo aprovado pelo Congresso em 2023 e regulamentado posteriormente. A implementa\u00e7\u00e3o ocorrer\u00e1 de forma gradual, com transi\u00e7\u00e3o prevista at\u00e9 2033.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de 2027, o IS passar\u00e1 a coexistir com a Contribui\u00e7\u00e3o sobre Bens e Servi\u00e7os (CBS), que substituir\u00e1 o Programa de Integra\u00e7\u00e3o Social (PIS) e a Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (Cofins) e parte do Imposto sobre Produtos Industrializados (IPI).<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Or\u00e7amento de 2027, o governo estima R$ 636 bilh\u00f5es de arrecada\u00e7\u00e3o com a CBS. Somados aos R$ 41,9 bilh\u00f5es previstos para o Imposto Seletivo, os dois novos tributos devem gerar R$ 677,9 bilh\u00f5es no pr\u00f3ximo ano.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A previs\u00e3o de receitas com os novos tributos \u00e9 considerada importante para o equil\u00edbrio das contas p\u00fablicas durante a transi\u00e7\u00e3o para o novo modelo tribut\u00e1rio.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cr\u00edticas do setor<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Produtores dos segmentos atingidos pelo Imposto Seletivo alegam que cigarros, bebidas alco\u00f3licas e outros produtos t\u00eam elevada carga tribut\u00e1ria no Brasil.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Representantes do setor avaliam que aumentos adicionais podem reduzir margens de lucro e provocar repasses aos pre\u00e7os. Tamb\u00e9m apontam riscos de demiss\u00f5es e crescimento do mercado ilegal caso a tributa\u00e7\u00e3o seja considerada excessiva.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O governo, por outro lado, sustenta que o Imposto Seletivo ter\u00e1 n\u00e3o apenas fun\u00e7\u00e3o arrecadat\u00f3ria, mas tamb\u00e9m regulat\u00f3ria, justamente para reduzir o consumo de produtos com impactos negativos sobre a sa\u00fade e o meio ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criado pela reforma tribut\u00e1ria, o Imposto Seletivo (IS), apelidado como &#8220;imposto do pecado&#8221;, dever\u00e1 arrecadar R$ 41,9 bilh\u00f5es em 2027. A previs\u00e3o foi inclu\u00edda no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA), enviado nesta segunda-feira (31) ao Congresso Nacional. O tributo ser\u00e1 aplicado a produtos e atividades considerados prejudiciais \u00e0 sa\u00fade ou ao meio ambiente. Entre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25186,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-25185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais\" \/>\n<meta property=\"og:description\" content=\"Criado pela reforma tribut\u00e1ria, o Imposto Seletivo (IS), apelidado como &#8220;imposto do pecado&#8221;, dever\u00e1 arrecadar R$ 41,9 bilh\u00f5es em 2027. A previs\u00e3o foi inclu\u00edda no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA), enviado nesta segunda-feira (31) ao Congresso Nacional. O tributo ser\u00e1 aplicado a produtos e atividades considerados prejudiciais \u00e0 sa\u00fade ou ao meio ambiente. Entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Ponto Mais\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T12:53:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T12:54:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jornal Ponto Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Ponto Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\"},\"author\":{\"name\":\"Jornal Ponto Mais\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d\"},\"headline\":\"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027\",\"datePublished\":\"2026-09-01T12:53:42+00:00\",\"dateModified\":\"2026-09-01T12:54:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\"},\"wordCount\":759,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\",\"url\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\",\"name\":\"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais\",\"isPartOf\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp\",\"datePublished\":\"2026-09-01T12:53:42+00:00\",\"dateModified\":\"2026-09-01T12:54:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage\",\"url\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp\",\"contentUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalpontomais.com\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#website\",\"url\":\"https:\/\/jornalpontomais.com\/site\/\",\"name\":\"Jornal Ponto Mais\",\"description\":\"As principais not\u00edcias do Brasil e do mundo. Confira!\",\"publisher\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalpontomais.com\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\",\"name\":\"Jornal Ponto+\",\"url\":\"https:\/\/jornalpontomais.com\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png\",\"contentUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png\",\"width\":582,\"height\":148,\"caption\":\"Jornal Ponto+\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d\",\"name\":\"Jornal Ponto Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"caption\":\"Jornal Ponto Mais\"},\"sameAs\":[\"https:\/\/jornalpontomais.com\/site\",\"jornalpontomais\"],\"url\":\"https:\/\/jornalpontomais.com\/site\/author\/jornalpontomais\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/","og_locale":"pt_BR","og_type":"article","og_title":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais","og_description":"Criado pela reforma tribut\u00e1ria, o Imposto Seletivo (IS), apelidado como &#8220;imposto do pecado&#8221;, dever\u00e1 arrecadar R$ 41,9 bilh\u00f5es em 2027. A previs\u00e3o foi inclu\u00edda no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA), enviado nesta segunda-feira (31) ao Congresso Nacional. O tributo ser\u00e1 aplicado a produtos e atividades considerados prejudiciais \u00e0 sa\u00fade ou ao meio ambiente. Entre [&hellip;]","og_url":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/","og_site_name":"Jornal Ponto Mais","article_published_time":"2026-09-01T12:53:42+00:00","article_modified_time":"2026-09-01T12:54:04+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp","type":"image\/webp"}],"author":"Jornal Ponto Mais","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Ponto Mais","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#article","isPartOf":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/"},"author":{"name":"Jornal Ponto Mais","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d"},"headline":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027","datePublished":"2026-09-01T12:53:42+00:00","dateModified":"2026-09-01T12:54:04+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/"},"wordCount":759,"commentCount":0,"publisher":{"@id":"https:\/\/jornalpontomais.com\/site\/#organization"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp","articleSection":["Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/","url":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/","name":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027 - Jornal Ponto Mais","isPartOf":{"@id":"https:\/\/jornalpontomais.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp","datePublished":"2026-09-01T12:53:42+00:00","dateModified":"2026-09-01T12:54:04+00:00","breadcrumb":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#primaryimage","url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp","contentUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/09\/vinhos_vac_abr_2907221151_0.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/jornalpontomais.com\/site\/2026\/09\/01\/arrecadacao-com-imposto-do-pecado-deve-chegar-a-r-419-bi-em-2027\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalpontomais.com\/site\/"},{"@type":"ListItem","position":2,"name":"Arrecada\u00e7\u00e3o com \u2018imposto do pecado\u2019 deve chegar a R$ 41,9 bi em 2027"}]},{"@type":"WebSite","@id":"https:\/\/jornalpontomais.com\/site\/#website","url":"https:\/\/jornalpontomais.com\/site\/","name":"Jornal Ponto Mais","description":"As principais not\u00edcias do Brasil e do mundo. Confira!","publisher":{"@id":"https:\/\/jornalpontomais.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalpontomais.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalpontomais.com\/site\/#organization","name":"Jornal Ponto+","url":"https:\/\/jornalpontomais.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png","contentUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png","width":582,"height":148,"caption":"Jornal Ponto+"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d","name":"Jornal Ponto Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","caption":"Jornal Ponto Mais"},"sameAs":["https:\/\/jornalpontomais.com\/site","jornalpontomais"],"url":"https:\/\/jornalpontomais.com\/site\/author\/jornalpontomais\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/25185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/comments?post=25185"}],"version-history":[{"count":1,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/25185\/revisions"}],"predecessor-version":[{"id":25187,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/25185\/revisions\/25187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/media\/25186"}],"wp:attachment":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/media?parent=25185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/categories?post=25185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/tags?post=25185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}