{"id":24430,"date":"2026-07-15T10:57:48","date_gmt":"2026-07-15T13:57:48","guid":{"rendered":"https:\/\/jornalpontomais.com\/site\/?p=24430"},"modified":"2026-07-15T11:08:52","modified_gmt":"2026-07-15T14:08:52","slug":"prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados","status":"publish","type":"post","link":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/","title":{"rendered":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados"},"content":{"rendered":"\n<p>A Prefeitura de Goi\u00e2nia, por meio da Secretaria Municipal de Sa\u00fade (SMS), alcan\u00e7ou a marca de <strong>mais de 7,5 mil atendimentos<\/strong> nas unidades b\u00e1sicas de sa\u00fade que passaram a funcionar aos s\u00e1bados. A iniciativa, implantada h\u00e1 um m\u00eas, busca ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os da Aten\u00e7\u00e3o Prim\u00e1ria, especialmente para quem encontra dificuldades para buscar atendimento durante os dias \u00fateis.<br><br><\/p>\n\n\n\n<p>Somente no \u00faltimo s\u00e1bado (11), as sete unidades abertas \u2014 distribu\u00eddas pelos distritos sanit\u00e1rios da capital \u2014 realizaram mais de mil atendimentos. Entre os servi\u00e7os oferecidos est\u00e3o consultas m\u00e9dicas e de enfermagem, vacina\u00e7\u00e3o, atendimento odontol\u00f3gico, coleta de exames laboratoriais, testes r\u00e1pidos, acompanhamento de pacientes com doen\u00e7as cr\u00f4nicas, dispensa\u00e7\u00e3o de medicamentos, inser\u00e7\u00e3o do Implanon, planejamento familiar e a\u00e7\u00f5es de promo\u00e7\u00e3o e preven\u00e7\u00e3o \u00e0 sa\u00fade.<br><br><\/p>\n\n\n\n<p>Segundo o secret\u00e1rio municipal de Sa\u00fade, Luiz Pellizzer, a abertura das unidades aos fins de semana tem facilitado o acesso da popula\u00e7\u00e3o aos servi\u00e7os b\u00e1sicos e contribu\u00eddo para reduzir a procura desnecess\u00e1ria por unidades de urg\u00eancia e emerg\u00eancia. A medida beneficia principalmente trabalhadores que n\u00e3o conseguem comparecer \u00e0s unidades durante o expediente comercial.<br><br><\/p>\n\n\n\n<p>Usu\u00e1rios tamb\u00e9m destacam a praticidade da iniciativa. Fam\u00edlias t\u00eam aproveitado o funcionamento aos s\u00e1bados para realizar consultas, atualizar a vacina\u00e7\u00e3o, fazer exames e retirar medicamentos em um \u00fanico dia, sem comprometer a rotina de trabalho durante a semana.<br><br><\/p>\n\n\n\n<p>No pr\u00f3ximo s\u00e1bado (18), seis unidades estar\u00e3o abertas para atendimento \u00e0 popula\u00e7\u00e3o: as Unidades de Sa\u00fade da Fam\u00edlia (USFs) Itatiaia, Novo Planalto, Jardim Mirabel, Vila Santa Helena e Vila Boa, al\u00e9m do Cais Amendoeiras\/Aroeiras. A rela\u00e7\u00e3o das unidades participantes \u00e9 divulgada semanalmente pelos canais oficiais da Secretaria Municipal de Sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Goi\u00e2nia, por meio da Secretaria Municipal de Sa\u00fade (SMS), alcan\u00e7ou a marca de mais de 7,5 mil atendimentos nas unidades b\u00e1sicas de sa\u00fade que passaram a funcionar aos s\u00e1bados. A iniciativa, implantada h\u00e1 um m\u00eas, busca ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os da Aten\u00e7\u00e3o Prim\u00e1ria, especialmente para quem encontra dificuldades para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24431,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-24430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Goi\u00e2nia, por meio da Secretaria Municipal de Sa\u00fade (SMS), alcan\u00e7ou a marca de mais de 7,5 mil atendimentos nas unidades b\u00e1sicas de sa\u00fade que passaram a funcionar aos s\u00e1bados. A iniciativa, implantada h\u00e1 um m\u00eas, busca ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os da Aten\u00e7\u00e3o Prim\u00e1ria, especialmente para quem encontra dificuldades para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Ponto Mais\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T13:57:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T14:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Ponto Mais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Ponto Mais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\"},\"author\":{\"name\":\"Jornal Ponto Mais\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d\"},\"headline\":\"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados\",\"datePublished\":\"2026-07-15T13:57:48+00:00\",\"dateModified\":\"2026-07-15T14:08:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\",\"url\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\",\"name\":\"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais\",\"isPartOf\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg\",\"datePublished\":\"2026-07-15T13:57:48+00:00\",\"dateModified\":\"2026-07-15T14:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage\",\"url\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg\",\"contentUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalpontomais.com\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#website\",\"url\":\"https:\/\/jornalpontomais.com\/site\/\",\"name\":\"Jornal Ponto Mais\",\"description\":\"As principais not\u00edcias do Brasil e do mundo. Confira!\",\"publisher\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalpontomais.com\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#organization\",\"name\":\"Jornal Ponto+\",\"url\":\"https:\/\/jornalpontomais.com\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png\",\"contentUrl\":\"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png\",\"width\":582,\"height\":148,\"caption\":\"Jornal Ponto+\"},\"image\":{\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d\",\"name\":\"Jornal Ponto Mais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g\",\"caption\":\"Jornal Ponto Mais\"},\"sameAs\":[\"https:\/\/jornalpontomais.com\/site\",\"jornalpontomais\"],\"url\":\"https:\/\/jornalpontomais.com\/site\/author\/jornalpontomais\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais","og_description":"A Prefeitura de Goi\u00e2nia, por meio da Secretaria Municipal de Sa\u00fade (SMS), alcan\u00e7ou a marca de mais de 7,5 mil atendimentos nas unidades b\u00e1sicas de sa\u00fade que passaram a funcionar aos s\u00e1bados. A iniciativa, implantada h\u00e1 um m\u00eas, busca ampliar o acesso da popula\u00e7\u00e3o aos servi\u00e7os da Aten\u00e7\u00e3o Prim\u00e1ria, especialmente para quem encontra dificuldades para [&hellip;]","og_url":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/","og_site_name":"Jornal Ponto Mais","article_published_time":"2026-07-15T13:57:48+00:00","article_modified_time":"2026-07-15T14:08:52+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg","type":"image\/jpeg"}],"author":"Jornal Ponto Mais","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Ponto Mais","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#article","isPartOf":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/"},"author":{"name":"Jornal Ponto Mais","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d"},"headline":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados","datePublished":"2026-07-15T13:57:48+00:00","dateModified":"2026-07-15T14:08:52+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/jornalpontomais.com\/site\/#organization"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/","url":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/","name":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados - Jornal Ponto Mais","isPartOf":{"@id":"https:\/\/jornalpontomais.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg","datePublished":"2026-07-15T13:57:48+00:00","dateModified":"2026-07-15T14:08:52+00:00","breadcrumb":{"@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#primaryimage","url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg","contentUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2026\/07\/saude.jpeg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/jornalpontomais.com\/site\/2026\/07\/15\/prefeitura-de-goiania-ultrapassa-75-mil-atendimentos-em-ubss-abertas-aos-sabados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalpontomais.com\/site\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de Goi\u00e2nia ultrapassa 7,5 mil atendimentos em UBSs abertas aos s\u00e1bados"}]},{"@type":"WebSite","@id":"https:\/\/jornalpontomais.com\/site\/#website","url":"https:\/\/jornalpontomais.com\/site\/","name":"Jornal Ponto Mais","description":"As principais not\u00edcias do Brasil e do mundo. Confira!","publisher":{"@id":"https:\/\/jornalpontomais.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalpontomais.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalpontomais.com\/site\/#organization","name":"Jornal Ponto+","url":"https:\/\/jornalpontomais.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png","contentUrl":"https:\/\/jornalpontomais.com\/site\/wp-content\/uploads\/2022\/01\/marca.png","width":582,"height":148,"caption":"Jornal Ponto+"},"image":{"@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalpontomais.com\/site\/#\/schema\/person\/18323f0b0f1355f2490721c48389fe9d","name":"Jornal Ponto Mais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ee0a9b7fe10fe32bdec8bc086e871e41eb5f4f6ecbcb7b4f2fe0d92d831405f?s=96&d=mm&r=g","caption":"Jornal Ponto Mais"},"sameAs":["https:\/\/jornalpontomais.com\/site","jornalpontomais"],"url":"https:\/\/jornalpontomais.com\/site\/author\/jornalpontomais\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/24430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/comments?post=24430"}],"version-history":[{"count":1,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/24430\/revisions"}],"predecessor-version":[{"id":24432,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/posts\/24430\/revisions\/24432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/media\/24431"}],"wp:attachment":[{"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/media?parent=24430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/categories?post=24430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalpontomais.com\/site\/wp-json\/wp\/v2\/tags?post=24430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}